{"id":926271,"date":"2025-04-06T15:26:29","date_gmt":"2025-04-06T18:26:29","guid":{"rendered":"https:\/\/www.pm.pb.gov.br\/portal\/?p=926271"},"modified":"2025-04-06T15:26:31","modified_gmt":"2025-04-06T18:26:31","slug":"policia-militar-realiza-prisao-por-trafico-de-drogas-e-apreende-arma-de-fogo-em-cabedelo","status":"publish","type":"post","link":"https:\/\/www.pm.pb.gov.br\/portal\/2025\/04\/06\/policia-militar-realiza-prisao-por-trafico-de-drogas-e-apreende-arma-de-fogo-em-cabedelo\/","title":{"rendered":"Pol\u00edcia Militar realiza pris\u00e3o por tr\u00e1fico de drogas e apreende arma de fogo em Cabedelo"},"content":{"rendered":"\n<p>Na tarde deste domingo (06), policiais militares da CPC\u00e3es prenderam um suspeito por tr\u00e1fico de drogas em Cabedelo-PB. Al\u00e9m das drogas, com o suspeito foi apreendida uma arma de fogo.<strong><\/strong><\/p>\n\n\n\n<p>A equipe policial estava em rondas na localidade conhecida por \u201cTravessa da Matan\u00e7a\u201d, em Cabedelo, quando visualizou alguns suspeitos que correram ao perceberem os policiais, sendo um deles alcan\u00e7ado. Na abordagem ao suspeito, foram encontrados: 41 sacol\u00e9s de maconha, 25 trouxinhas de coca\u00edna, dinheiro e 01 rev\u00f3lver, calibre 22, com 8 muni\u00e7\u00f5es intactas.<\/p>\n\n\n\n<p>O suspeito preso e o material apreendido foram encaminhados \u00e0 Delegacia de Pol\u00edcia Civil para as provid\u00eancias cab\u00edveis.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Na tarde deste domingo (06), policiais militares da CPC\u00e3es prenderam um suspeito por tr\u00e1fico de drogas em Cabedelo-PB. Al\u00e9m das<\/p>\n","protected":false},"author":5,"featured_media":926272,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_exactmetrics_skip_tracking":false,"_exactmetrics_sitenote_active":false,"_exactmetrics_sitenote_note":"","_exactmetrics_sitenote_category":0,"footnotes":""},"categories":[4],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v22.0 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Pol\u00edcia Militar realiza pris\u00e3o por tr\u00e1fico de drogas e apreende arma de fogo em Cabedelo - Pol\u00edcia Militar da Para\u00edba<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.pm.pb.gov.br\/portal\/2025\/04\/06\/policia-militar-realiza-prisao-por-trafico-de-drogas-e-apreende-arma-de-fogo-em-cabedelo\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Pol\u00edcia Militar realiza pris\u00e3o por tr\u00e1fico de drogas e apreende arma de fogo em Cabedelo - Pol\u00edcia Militar da Para\u00edba\" \/>\n<meta property=\"og:description\" content=\"Na tarde deste domingo (06), policiais militares da CPC\u00e3es prenderam um suspeito por tr\u00e1fico de drogas em Cabedelo-PB. Al\u00e9m das\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.pm.pb.gov.br\/portal\/2025\/04\/06\/policia-militar-realiza-prisao-por-trafico-de-drogas-e-apreende-arma-de-fogo-em-cabedelo\/\" \/>\n<meta property=\"og:site_name\" content=\"Pol\u00edcia Militar da Para\u00edba\" \/>\n<meta property=\"article:published_time\" content=\"2025-04-06T18:26:29+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-04-06T18:26:31+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/www.pm.pb.gov.br\/portal\/wp-content\/uploads\/2025\/04\/drogas3.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"667\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Assessoria de Imprensa da PMPB\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Assessoria de Imprensa da PMPB\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.pm.pb.gov.br\/portal\/2025\/04\/06\/policia-militar-realiza-prisao-por-trafico-de-drogas-e-apreende-arma-de-fogo-em-cabedelo\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.pm.pb.gov.br\/portal\/2025\/04\/06\/policia-militar-realiza-prisao-por-trafico-de-drogas-e-apreende-arma-de-fogo-em-cabedelo\/\"},\"author\":{\"name\":\"Assessoria de Imprensa da PMPB\",\"@id\":\"https:\/\/www.pm.pb.gov.br\/portal\/#\/schema\/person\/e8454f46651c3ecf0e1ba3c1666d9947\"},\"headline\":\"Pol\u00edcia Militar realiza pris\u00e3o por tr\u00e1fico de drogas e apreende arma de fogo em Cabedelo\",\"datePublished\":\"2025-04-06T18:26:29+00:00\",\"dateModified\":\"2025-04-06T18:26:31+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.pm.pb.gov.br\/portal\/2025\/04\/06\/policia-militar-realiza-prisao-por-trafico-de-drogas-e-apreende-arma-de-fogo-em-cabedelo\/\"},\"wordCount\":124,\"publisher\":{\"@id\":\"https:\/\/www.pm.pb.gov.br\/portal\/#organization\"},\"articleSection\":[\"A\u00e7\u00f5es Policiais\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.pm.pb.gov.br\/portal\/2025\/04\/06\/policia-militar-realiza-prisao-por-trafico-de-drogas-e-apreende-arma-de-fogo-em-cabedelo\/\",\"url\":\"https:\/\/www.pm.pb.gov.br\/portal\/2025\/04\/06\/policia-militar-realiza-prisao-por-trafico-de-drogas-e-apreende-arma-de-fogo-em-cabedelo\/\",\"name\":\"Pol\u00edcia Militar realiza pris\u00e3o por tr\u00e1fico de drogas e apreende arma de fogo em Cabedelo - Pol\u00edcia Militar da Para\u00edba\",\"isPartOf\":{\"@id\":\"https:\/\/www.pm.pb.gov.br\/portal\/#website\"},\"datePublished\":\"2025-04-06T18:26:29+00:00\",\"dateModified\":\"2025-04-06T18:26:31+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.pm.pb.gov.br\/portal\/2025\/04\/06\/policia-militar-realiza-prisao-por-trafico-de-drogas-e-apreende-arma-de-fogo-em-cabedelo\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.pm.pb.gov.br\/portal\/2025\/04\/06\/policia-militar-realiza-prisao-por-trafico-de-drogas-e-apreende-arma-de-fogo-em-cabedelo\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.pm.pb.gov.br\/portal\/2025\/04\/06\/policia-militar-realiza-prisao-por-trafico-de-drogas-e-apreende-arma-de-fogo-em-cabedelo\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/www.pm.pb.gov.br\/portal\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Pol\u00edcia Militar realiza pris\u00e3o por tr\u00e1fico de drogas e apreende arma de fogo em Cabedelo\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.pm.pb.gov.br\/portal\/#website\",\"url\":\"https:\/\/www.pm.pb.gov.br\/portal\/\",\"name\":\"Pol\u00edcia Militar da Para\u00edba\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/www.pm.pb.gov.br\/portal\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.pm.pb.gov.br\/portal\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.pm.pb.gov.br\/portal\/#organization\",\"name\":\"Pol\u00edcia Militar da Para\u00edba\",\"url\":\"https:\/\/www.pm.pb.gov.br\/portal\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.pm.pb.gov.br\/portal\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.pm.pb.gov.br\/portal\/wp-content\/uploads\/2025\/03\/cropped-logo-site-mag2-1.png\",\"contentUrl\":\"https:\/\/www.pm.pb.gov.br\/portal\/wp-content\/uploads\/2025\/03\/cropped-logo-site-mag2-1.png\",\"width\":320,\"height\":90,\"caption\":\"Pol\u00edcia Militar da Para\u00edba\"},\"image\":{\"@id\":\"https:\/\/www.pm.pb.gov.br\/portal\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.pm.pb.gov.br\/portal\/#\/schema\/person\/e8454f46651c3ecf0e1ba3c1666d9947\",\"name\":\"Assessoria de Imprensa da PMPB\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.pm.pb.gov.br\/portal\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/2efe197438265d1e90bd98c4c8e1acf8?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/2efe197438265d1e90bd98c4c8e1acf8?s=96&d=mm&r=g\",\"caption\":\"Assessoria de Imprensa da PMPB\"},\"url\":\"https:\/\/www.pm.pb.gov.br\/portal\/author\/assessoria\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Pol\u00edcia Militar realiza pris\u00e3o por tr\u00e1fico de drogas e apreende arma de fogo em Cabedelo - Pol\u00edcia Militar da Para\u00edba","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.pm.pb.gov.br\/portal\/2025\/04\/06\/policia-militar-realiza-prisao-por-trafico-de-drogas-e-apreende-arma-de-fogo-em-cabedelo\/","og_locale":"pt_BR","og_type":"article","og_title":"Pol\u00edcia Militar realiza pris\u00e3o por tr\u00e1fico de drogas e apreende arma de fogo em Cabedelo - Pol\u00edcia Militar da Para\u00edba","og_description":"Na tarde deste domingo (06), policiais militares da CPC\u00e3es prenderam um suspeito por tr\u00e1fico de drogas em Cabedelo-PB. Al\u00e9m das","og_url":"https:\/\/www.pm.pb.gov.br\/portal\/2025\/04\/06\/policia-militar-realiza-prisao-por-trafico-de-drogas-e-apreende-arma-de-fogo-em-cabedelo\/","og_site_name":"Pol\u00edcia Militar da Para\u00edba","article_published_time":"2025-04-06T18:26:29+00:00","article_modified_time":"2025-04-06T18:26:31+00:00","og_image":[{"width":1200,"height":667,"url":"http:\/\/www.pm.pb.gov.br\/portal\/wp-content\/uploads\/2025\/04\/drogas3.png","type":"image\/png"}],"author":"Assessoria de Imprensa da PMPB","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Assessoria de Imprensa da PMPB","Est. tempo de leitura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.pm.pb.gov.br\/portal\/2025\/04\/06\/policia-militar-realiza-prisao-por-trafico-de-drogas-e-apreende-arma-de-fogo-em-cabedelo\/#article","isPartOf":{"@id":"https:\/\/www.pm.pb.gov.br\/portal\/2025\/04\/06\/policia-militar-realiza-prisao-por-trafico-de-drogas-e-apreende-arma-de-fogo-em-cabedelo\/"},"author":{"name":"Assessoria de Imprensa da PMPB","@id":"https:\/\/www.pm.pb.gov.br\/portal\/#\/schema\/person\/e8454f46651c3ecf0e1ba3c1666d9947"},"headline":"Pol\u00edcia Militar realiza pris\u00e3o por tr\u00e1fico de drogas e apreende arma de fogo em Cabedelo","datePublished":"2025-04-06T18:26:29+00:00","dateModified":"2025-04-06T18:26:31+00:00","mainEntityOfPage":{"@id":"https:\/\/www.pm.pb.gov.br\/portal\/2025\/04\/06\/policia-militar-realiza-prisao-por-trafico-de-drogas-e-apreende-arma-de-fogo-em-cabedelo\/"},"wordCount":124,"publisher":{"@id":"https:\/\/www.pm.pb.gov.br\/portal\/#organization"},"articleSection":["A\u00e7\u00f5es Policiais"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/www.pm.pb.gov.br\/portal\/2025\/04\/06\/policia-militar-realiza-prisao-por-trafico-de-drogas-e-apreende-arma-de-fogo-em-cabedelo\/","url":"https:\/\/www.pm.pb.gov.br\/portal\/2025\/04\/06\/policia-militar-realiza-prisao-por-trafico-de-drogas-e-apreende-arma-de-fogo-em-cabedelo\/","name":"Pol\u00edcia Militar realiza pris\u00e3o por tr\u00e1fico de drogas e apreende arma de fogo em Cabedelo - Pol\u00edcia Militar da Para\u00edba","isPartOf":{"@id":"https:\/\/www.pm.pb.gov.br\/portal\/#website"},"datePublished":"2025-04-06T18:26:29+00:00","dateModified":"2025-04-06T18:26:31+00:00","breadcrumb":{"@id":"https:\/\/www.pm.pb.gov.br\/portal\/2025\/04\/06\/policia-militar-realiza-prisao-por-trafico-de-drogas-e-apreende-arma-de-fogo-em-cabedelo\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.pm.pb.gov.br\/portal\/2025\/04\/06\/policia-militar-realiza-prisao-por-trafico-de-drogas-e-apreende-arma-de-fogo-em-cabedelo\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.pm.pb.gov.br\/portal\/2025\/04\/06\/policia-militar-realiza-prisao-por-trafico-de-drogas-e-apreende-arma-de-fogo-em-cabedelo\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.pm.pb.gov.br\/portal\/"},{"@type":"ListItem","position":2,"name":"Pol\u00edcia Militar realiza pris\u00e3o por tr\u00e1fico de drogas e apreende arma de fogo em Cabedelo"}]},{"@type":"WebSite","@id":"https:\/\/www.pm.pb.gov.br\/portal\/#website","url":"https:\/\/www.pm.pb.gov.br\/portal\/","name":"Pol\u00edcia Militar da Para\u00edba","description":"","publisher":{"@id":"https:\/\/www.pm.pb.gov.br\/portal\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.pm.pb.gov.br\/portal\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/www.pm.pb.gov.br\/portal\/#organization","name":"Pol\u00edcia Militar da Para\u00edba","url":"https:\/\/www.pm.pb.gov.br\/portal\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.pm.pb.gov.br\/portal\/#\/schema\/logo\/image\/","url":"https:\/\/www.pm.pb.gov.br\/portal\/wp-content\/uploads\/2025\/03\/cropped-logo-site-mag2-1.png","contentUrl":"https:\/\/www.pm.pb.gov.br\/portal\/wp-content\/uploads\/2025\/03\/cropped-logo-site-mag2-1.png","width":320,"height":90,"caption":"Pol\u00edcia Militar da Para\u00edba"},"image":{"@id":"https:\/\/www.pm.pb.gov.br\/portal\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.pm.pb.gov.br\/portal\/#\/schema\/person\/e8454f46651c3ecf0e1ba3c1666d9947","name":"Assessoria de Imprensa da PMPB","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.pm.pb.gov.br\/portal\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/2efe197438265d1e90bd98c4c8e1acf8?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/2efe197438265d1e90bd98c4c8e1acf8?s=96&d=mm&r=g","caption":"Assessoria de Imprensa da PMPB"},"url":"https:\/\/www.pm.pb.gov.br\/portal\/author\/assessoria\/"}]}},"_links":{"self":[{"href":"https:\/\/www.pm.pb.gov.br\/portal\/wp-json\/wp\/v2\/posts\/926271"}],"collection":[{"href":"https:\/\/www.pm.pb.gov.br\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.pm.pb.gov.br\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.pm.pb.gov.br\/portal\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/www.pm.pb.gov.br\/portal\/wp-json\/wp\/v2\/comments?post=926271"}],"version-history":[{"count":1,"href":"https:\/\/www.pm.pb.gov.br\/portal\/wp-json\/wp\/v2\/posts\/926271\/revisions"}],"predecessor-version":[{"id":926273,"href":"https:\/\/www.pm.pb.gov.br\/portal\/wp-json\/wp\/v2\/posts\/926271\/revisions\/926273"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.pm.pb.gov.br\/portal\/wp-json\/wp\/v2\/media\/926272"}],"wp:attachment":[{"href":"https:\/\/www.pm.pb.gov.br\/portal\/wp-json\/wp\/v2\/media?parent=926271"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.pm.pb.gov.br\/portal\/wp-json\/wp\/v2\/categories?post=926271"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.pm.pb.gov.br\/portal\/wp-json\/wp\/v2\/tags?post=926271"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}