{"id":896451,"date":"2017-12-22T09:12:01","date_gmt":"2017-12-22T12:12:01","guid":{"rendered":"http:\/\/www.pm.pb.gov.br\/portal\/?p=896451"},"modified":"2017-12-22T09:12:01","modified_gmt":"2017-12-22T12:12:01","slug":"crimes-contra-a-vida-devem-reduzir-pelo-6o-ano-consecutivo-na-paraiba","status":"publish","type":"post","link":"https:\/\/www.pm.pb.gov.br\/portal\/2017\/12\/22\/crimes-contra-a-vida-devem-reduzir-pelo-6o-ano-consecutivo-na-paraiba\/","title":{"rendered":"Crimes contra a vida devem reduzir pelo 6\u00ba ano consecutivo na Para\u00edba"},"content":{"rendered":"<p style=\"text-align: justify;\">A Para\u00edba dever\u00e1 ser o \u00fanico estado do Brasil a reduzir assassinatos por seis anos consecutivos. \u00c9 o que aponta o relat\u00f3rio do N\u00facleo de An\u00e1lise Criminal e Estat\u00edstica (Nace) da Secretaria da Seguran\u00e7a e da Defesa Social (Sesds), apresentado nesta quinta-feira (21), durante reuni\u00e3o realizada entre o governador Ricardo Coutinho e gestores das Pol\u00edcias Civil, Militar e Corpo de Bombeiros, no Pal\u00e1cio da Reden\u00e7\u00e3o, em Jo\u00e3o Pessoa (foto acima). Segundo os n\u00fameros, este ano, de janeiro a novembro, a Para\u00edba acumula 2,5% de queda nas ocorr\u00eancias de Crimes Violentos Letais Intencionais (CVLI), com 1.172 casos, contra 1.202 no mesmo per\u00edodo de 2016. Em 2011, o estado chegou a registrar 1.680 assassinatos. Em rela\u00e7\u00e3o aos homic\u00eddios por 100 mil habitantes, este ano a Para\u00edba pode chegar a uma taxa de 31,8, a segunda melhor projetada para os estados do Nordeste.<\/p>\n<p style=\"text-align: justify;\">Os assassinatos de mulheres tamb\u00e9m diminu\u00edram em territ\u00f3rio paraibano. Em 2017, de janeiro a novembro, foram 74 casos de CVLI com v\u00edtimas do sexo feminino e em 2016, no mesmo per\u00edodo, foram contabilizados 90 casos. Os homic\u00eddios de mulheres representam 6% do total de mortes por assassinatos no Estado.<\/p>\n<p style=\"text-align: justify;\">Na ocasi\u00e3o, o governador Ricardo Coutinho sancionou a Lei que regulamenta o Programa Para\u00edba Unida pela Paz, pol\u00edtica p\u00fablica fundamentada na defesa da vida e do patrim\u00f4nio, que busca promover e garantir a seguran\u00e7a, ordem p\u00fablica e paz social. \u201cEstamos registrando este Programa como uma Lei, ou seja, um instrumento cont\u00ednuo, uma pol\u00edtica p\u00fablica que ter\u00e1 seguimento a curto, m\u00e9dio e longo prazo. Os dados positivos, desde que implantamos o Para\u00edba Unida pela Paz, mostram que estamos no caminho correto\u201d, observou.<\/p>\n<p style=\"text-align: justify;\">O governador tamb\u00e9m aproveitou a oportunidade para agradecer a todos que comp\u00f5em as for\u00e7as de seguran\u00e7a no Estado pelo empenho e dedica\u00e7\u00e3o durante este ano e pedir que em 2018 o esfor\u00e7o na busca pela paz social continue ainda mais firme. \u201cMuito foi feito neste ano que estamos prestes a concluir, por\u00e9m \u00e9 preciso fazer ainda mais em 2018. O combate \u00e0 criminalidade deve ser constante e pede sempre muita determina\u00e7\u00e3o das for\u00e7as de seguran\u00e7a. Em poucos dias, estaremos fechando 2017 e provavelmente teremos mais um ano com redu\u00e7\u00e3o de homic\u00eddios, sendo o 6\u00ba ano consecutivo. Agrade\u00e7o o empenho de todos e que possamos entrar 2018 ainda mais empenhados, visando garantir a tranquilidade da popula\u00e7\u00e3o\u201d, concluiu.<\/p>\n<p style=\"text-align: justify;\">\u201cEste \u00e9 um momento importante, porque conclui simbolicamente, o ano de 2017 e tamb\u00e9m porque hoje o governador transformou o Para\u00edba Unida pela Paz em Lei, sendo algo que vai ficar para o futuro. Todos os resultados que alcan\u00e7amos, ao longo desses anos, s\u00e3o frutos de muito trabalho. Que tenhamos um final de ano produtivo e um 2018 com ainda mais determina\u00e7\u00e3o na busca pela paz\u201d, falou o secret\u00e1rio de Seguran\u00e7a e Defesa Social, Cl\u00e1udio Lima.<\/p>\n<p style=\"text-align: justify;\">Tamb\u00e9m estiveram presentes na reuni\u00e3o o comandante geral da Pol\u00edcia Militar, coronel Euller Chaves, o delegado geral da Pol\u00edcia Civil, Jo\u00e3o Alves, o comandante geral do Corpo de Bombeiros, coronel Jair Carneiro, o secret\u00e1rio da Administra\u00e7\u00e3o Penitenci\u00e1ria, Wagner Dorta, o chefe da Casa Militar, Anderson Pessoa, e outras autoridades.<\/p>\n<p style=\"text-align: justify;\"><strong>Dados<\/strong> &#8211; Ainda segundo dados do Nace, 10 das 21 \u00c1reas Integradas de Seguran\u00e7a P\u00fablica (Aisp) apresentam redu\u00e7\u00e3o na ocorr\u00eancia de assassinatos. A 1\u00aa Aisp tem 25 CVLI a menos na zona norte de Jo\u00e3o Pessoa. A mesma redu\u00e7\u00e3o foi verificada na \u00e1rea de Esperan\u00e7a (12\u00aa Aisp). A zona sul de Jo\u00e3o Pessoa (1\u00aa Aisp) tem menos 17 assassinatos. A 5\u00aa Aisp, de Santa Rita contabilizou menos 12 casos, a 7\u00aa Aisp de Mamanguape menos 11 casos. Sol\u00e2nea (3\u00aa Aisp) tem cinco homic\u00eddios a menos, a 4\u00aa Aisp de Bayeux menos quatro casos. Itaporanga (17\u00aa Aisp) registrou redu\u00e7\u00e3o de tr\u00eas casos e a 19\u00aa Aisp de Sousa tem menos um caso.<\/p>\n<p style=\"text-align: justify;\"><strong>Redu\u00e7\u00e3o de ataques a bancos<\/strong> \u2013 Este ano, houve uma diminui\u00e7\u00e3o de 25% das ocorr\u00eancias de crimes patrimoniais consumados envolvendo institui\u00e7\u00f5es banc\u00e1rias e ag\u00eancias dos Correios em territ\u00f3rio paraibano. Em 2017, de janeiro a novembro, o Nace contabilizou 79 casos, enquanto que no mesmo per\u00edodo do ano passado aconteceram 106 ocorr\u00eancias desse tipo. Houve 15% de redu\u00e7\u00e3o em rela\u00e7\u00e3o aos furtos com explos\u00e3o (75 contra 64 casos); e 64% em rela\u00e7\u00e3o a furtos com arrombamento (28 contra 10 casos). No que se refere aos roubos, foram cinco casos em 2017, em 11 meses.<\/p>\n<p style=\"text-align: justify;\">\u00a0<strong>Apreens\u00e3o de armas e drogas<\/strong> \u2013 Uma das a\u00e7\u00f5es realizadas pelas Pol\u00edcias da Para\u00edba para enfrentamento da viol\u00eancia \u00e9 a retirada de armas e drogas das ruas. Em rela\u00e7\u00e3o aos armamentos, 3.182 unidades de rev\u00f3lveres, pistolas e espingardas, entre outros, foram apreendidas em a\u00e7\u00f5es de seguran\u00e7a p\u00fablica. De 2011 a 2016, 18 mil armas que circulavam ilegalmente foram recolhidas pelas For\u00e7as de Seguran\u00e7a P\u00fablica.<\/p>\n<p style=\"text-align: justify;\">O total de entorpecentes apreendidos foi de 1.957,6 quilos de janeiro a novembro de 2017, e no ano passado 949,61 quilos, no mesmo per\u00edodo. Houve aumento em todos os tipos de drogas apreendidas: 56% de coca\u00edna (25,61 para 40,1 quilos); 68% de crack (50,9 para 85,7 quilos); e 110% de maconha (873,1 para 1.831,8 quilos).<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A Para\u00edba dever\u00e1 ser o \u00fanico estado do Brasil a reduzir assassinatos por seis anos consecutivos. \u00c9 o que aponta<\/p>\n","protected":false},"author":12,"featured_media":896450,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_exactmetrics_skip_tracking":false,"_exactmetrics_sitenote_active":false,"_exactmetrics_sitenote_note":"","_exactmetrics_sitenote_category":0,"footnotes":""},"categories":[4],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v22.0 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Crimes contra a vida devem reduzir pelo 6\u00ba ano consecutivo na Para\u00edba - Pol\u00edcia Militar da Para\u00edba<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.pm.pb.gov.br\/portal\/2017\/12\/22\/crimes-contra-a-vida-devem-reduzir-pelo-6o-ano-consecutivo-na-paraiba\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Crimes contra a vida devem reduzir pelo 6\u00ba ano consecutivo na Para\u00edba - Pol\u00edcia Militar da Para\u00edba\" \/>\n<meta property=\"og:description\" content=\"A Para\u00edba dever\u00e1 ser o \u00fanico estado do Brasil a reduzir assassinatos por seis anos consecutivos. \u00c9 o que aponta\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.pm.pb.gov.br\/portal\/2017\/12\/22\/crimes-contra-a-vida-devem-reduzir-pelo-6o-ano-consecutivo-na-paraiba\/\" \/>\n<meta property=\"og:site_name\" content=\"Pol\u00edcia Militar da Para\u00edba\" \/>\n<meta property=\"article:published_time\" content=\"2017-12-22T12:12:01+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.pm.pb.gov.br\/portal\/wp-content\/uploads\/2017\/12\/reuniao.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"445\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Tarcisio Oliveira\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Tarcisio Oliveira\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.pm.pb.gov.br\/portal\/2017\/12\/22\/crimes-contra-a-vida-devem-reduzir-pelo-6o-ano-consecutivo-na-paraiba\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.pm.pb.gov.br\/portal\/2017\/12\/22\/crimes-contra-a-vida-devem-reduzir-pelo-6o-ano-consecutivo-na-paraiba\/\"},\"author\":{\"name\":\"Tarcisio Oliveira\",\"@id\":\"https:\/\/www.pm.pb.gov.br\/portal\/#\/schema\/person\/f84f56dcc78ce4357054da888b8247fd\"},\"headline\":\"Crimes contra a vida devem reduzir pelo 6\u00ba ano consecutivo na Para\u00edba\",\"datePublished\":\"2017-12-22T12:12:01+00:00\",\"dateModified\":\"2017-12-22T12:12:01+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.pm.pb.gov.br\/portal\/2017\/12\/22\/crimes-contra-a-vida-devem-reduzir-pelo-6o-ano-consecutivo-na-paraiba\/\"},\"wordCount\":881,\"publisher\":{\"@id\":\"https:\/\/www.pm.pb.gov.br\/portal\/#organization\"},\"articleSection\":[\"A\u00e7\u00f5es Policiais\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.pm.pb.gov.br\/portal\/2017\/12\/22\/crimes-contra-a-vida-devem-reduzir-pelo-6o-ano-consecutivo-na-paraiba\/\",\"url\":\"https:\/\/www.pm.pb.gov.br\/portal\/2017\/12\/22\/crimes-contra-a-vida-devem-reduzir-pelo-6o-ano-consecutivo-na-paraiba\/\",\"name\":\"Crimes contra a vida devem reduzir pelo 6\u00ba ano consecutivo na Para\u00edba - Pol\u00edcia Militar da Para\u00edba\",\"isPartOf\":{\"@id\":\"https:\/\/www.pm.pb.gov.br\/portal\/#website\"},\"datePublished\":\"2017-12-22T12:12:01+00:00\",\"dateModified\":\"2017-12-22T12:12:01+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.pm.pb.gov.br\/portal\/2017\/12\/22\/crimes-contra-a-vida-devem-reduzir-pelo-6o-ano-consecutivo-na-paraiba\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.pm.pb.gov.br\/portal\/2017\/12\/22\/crimes-contra-a-vida-devem-reduzir-pelo-6o-ano-consecutivo-na-paraiba\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.pm.pb.gov.br\/portal\/2017\/12\/22\/crimes-contra-a-vida-devem-reduzir-pelo-6o-ano-consecutivo-na-paraiba\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/www.pm.pb.gov.br\/portal\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Crimes contra a vida devem reduzir pelo 6\u00ba ano consecutivo na Para\u00edba\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.pm.pb.gov.br\/portal\/#website\",\"url\":\"https:\/\/www.pm.pb.gov.br\/portal\/\",\"name\":\"Pol\u00edcia Militar da Para\u00edba\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/www.pm.pb.gov.br\/portal\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.pm.pb.gov.br\/portal\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.pm.pb.gov.br\/portal\/#organization\",\"name\":\"Pol\u00edcia Militar da Para\u00edba\",\"url\":\"https:\/\/www.pm.pb.gov.br\/portal\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.pm.pb.gov.br\/portal\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.pm.pb.gov.br\/portal\/wp-content\/uploads\/2025\/03\/cropped-logo-site-mag2-1.png\",\"contentUrl\":\"https:\/\/www.pm.pb.gov.br\/portal\/wp-content\/uploads\/2025\/03\/cropped-logo-site-mag2-1.png\",\"width\":320,\"height\":90,\"caption\":\"Pol\u00edcia Militar da Para\u00edba\"},\"image\":{\"@id\":\"https:\/\/www.pm.pb.gov.br\/portal\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.pm.pb.gov.br\/portal\/#\/schema\/person\/f84f56dcc78ce4357054da888b8247fd\",\"name\":\"Tarcisio Oliveira\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.pm.pb.gov.br\/portal\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/72917b630b69d31cd0297507f34bac97?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/72917b630b69d31cd0297507f34bac97?s=96&d=mm&r=g\",\"caption\":\"Tarcisio Oliveira\"},\"url\":\"https:\/\/www.pm.pb.gov.br\/portal\/author\/tarcisio\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Crimes contra a vida devem reduzir pelo 6\u00ba ano consecutivo na Para\u00edba - Pol\u00edcia Militar da Para\u00edba","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.pm.pb.gov.br\/portal\/2017\/12\/22\/crimes-contra-a-vida-devem-reduzir-pelo-6o-ano-consecutivo-na-paraiba\/","og_locale":"pt_BR","og_type":"article","og_title":"Crimes contra a vida devem reduzir pelo 6\u00ba ano consecutivo na Para\u00edba - Pol\u00edcia Militar da Para\u00edba","og_description":"A Para\u00edba dever\u00e1 ser o \u00fanico estado do Brasil a reduzir assassinatos por seis anos consecutivos. \u00c9 o que aponta","og_url":"https:\/\/www.pm.pb.gov.br\/portal\/2017\/12\/22\/crimes-contra-a-vida-devem-reduzir-pelo-6o-ano-consecutivo-na-paraiba\/","og_site_name":"Pol\u00edcia Militar da Para\u00edba","article_published_time":"2017-12-22T12:12:01+00:00","og_image":[{"width":800,"height":445,"url":"https:\/\/www.pm.pb.gov.br\/portal\/wp-content\/uploads\/2017\/12\/reuniao.jpg","type":"image\/jpeg"}],"author":"Tarcisio Oliveira","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Tarcisio Oliveira","Est. tempo de leitura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.pm.pb.gov.br\/portal\/2017\/12\/22\/crimes-contra-a-vida-devem-reduzir-pelo-6o-ano-consecutivo-na-paraiba\/#article","isPartOf":{"@id":"https:\/\/www.pm.pb.gov.br\/portal\/2017\/12\/22\/crimes-contra-a-vida-devem-reduzir-pelo-6o-ano-consecutivo-na-paraiba\/"},"author":{"name":"Tarcisio Oliveira","@id":"https:\/\/www.pm.pb.gov.br\/portal\/#\/schema\/person\/f84f56dcc78ce4357054da888b8247fd"},"headline":"Crimes contra a vida devem reduzir pelo 6\u00ba ano consecutivo na Para\u00edba","datePublished":"2017-12-22T12:12:01+00:00","dateModified":"2017-12-22T12:12:01+00:00","mainEntityOfPage":{"@id":"https:\/\/www.pm.pb.gov.br\/portal\/2017\/12\/22\/crimes-contra-a-vida-devem-reduzir-pelo-6o-ano-consecutivo-na-paraiba\/"},"wordCount":881,"publisher":{"@id":"https:\/\/www.pm.pb.gov.br\/portal\/#organization"},"articleSection":["A\u00e7\u00f5es Policiais"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/www.pm.pb.gov.br\/portal\/2017\/12\/22\/crimes-contra-a-vida-devem-reduzir-pelo-6o-ano-consecutivo-na-paraiba\/","url":"https:\/\/www.pm.pb.gov.br\/portal\/2017\/12\/22\/crimes-contra-a-vida-devem-reduzir-pelo-6o-ano-consecutivo-na-paraiba\/","name":"Crimes contra a vida devem reduzir pelo 6\u00ba ano consecutivo na Para\u00edba - Pol\u00edcia Militar da Para\u00edba","isPartOf":{"@id":"https:\/\/www.pm.pb.gov.br\/portal\/#website"},"datePublished":"2017-12-22T12:12:01+00:00","dateModified":"2017-12-22T12:12:01+00:00","breadcrumb":{"@id":"https:\/\/www.pm.pb.gov.br\/portal\/2017\/12\/22\/crimes-contra-a-vida-devem-reduzir-pelo-6o-ano-consecutivo-na-paraiba\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.pm.pb.gov.br\/portal\/2017\/12\/22\/crimes-contra-a-vida-devem-reduzir-pelo-6o-ano-consecutivo-na-paraiba\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.pm.pb.gov.br\/portal\/2017\/12\/22\/crimes-contra-a-vida-devem-reduzir-pelo-6o-ano-consecutivo-na-paraiba\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.pm.pb.gov.br\/portal\/"},{"@type":"ListItem","position":2,"name":"Crimes contra a vida devem reduzir pelo 6\u00ba ano consecutivo na Para\u00edba"}]},{"@type":"WebSite","@id":"https:\/\/www.pm.pb.gov.br\/portal\/#website","url":"https:\/\/www.pm.pb.gov.br\/portal\/","name":"Pol\u00edcia Militar da Para\u00edba","description":"","publisher":{"@id":"https:\/\/www.pm.pb.gov.br\/portal\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.pm.pb.gov.br\/portal\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/www.pm.pb.gov.br\/portal\/#organization","name":"Pol\u00edcia Militar da Para\u00edba","url":"https:\/\/www.pm.pb.gov.br\/portal\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.pm.pb.gov.br\/portal\/#\/schema\/logo\/image\/","url":"https:\/\/www.pm.pb.gov.br\/portal\/wp-content\/uploads\/2025\/03\/cropped-logo-site-mag2-1.png","contentUrl":"https:\/\/www.pm.pb.gov.br\/portal\/wp-content\/uploads\/2025\/03\/cropped-logo-site-mag2-1.png","width":320,"height":90,"caption":"Pol\u00edcia Militar da Para\u00edba"},"image":{"@id":"https:\/\/www.pm.pb.gov.br\/portal\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.pm.pb.gov.br\/portal\/#\/schema\/person\/f84f56dcc78ce4357054da888b8247fd","name":"Tarcisio Oliveira","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.pm.pb.gov.br\/portal\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/72917b630b69d31cd0297507f34bac97?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/72917b630b69d31cd0297507f34bac97?s=96&d=mm&r=g","caption":"Tarcisio Oliveira"},"url":"https:\/\/www.pm.pb.gov.br\/portal\/author\/tarcisio\/"}]}},"_links":{"self":[{"href":"https:\/\/www.pm.pb.gov.br\/portal\/wp-json\/wp\/v2\/posts\/896451"}],"collection":[{"href":"https:\/\/www.pm.pb.gov.br\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.pm.pb.gov.br\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.pm.pb.gov.br\/portal\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/www.pm.pb.gov.br\/portal\/wp-json\/wp\/v2\/comments?post=896451"}],"version-history":[{"count":2,"href":"https:\/\/www.pm.pb.gov.br\/portal\/wp-json\/wp\/v2\/posts\/896451\/revisions"}],"predecessor-version":[{"id":896453,"href":"https:\/\/www.pm.pb.gov.br\/portal\/wp-json\/wp\/v2\/posts\/896451\/revisions\/896453"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.pm.pb.gov.br\/portal\/wp-json\/wp\/v2\/media\/896450"}],"wp:attachment":[{"href":"https:\/\/www.pm.pb.gov.br\/portal\/wp-json\/wp\/v2\/media?parent=896451"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.pm.pb.gov.br\/portal\/wp-json\/wp\/v2\/categories?post=896451"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.pm.pb.gov.br\/portal\/wp-json\/wp\/v2\/tags?post=896451"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}